{"id":175605,"date":"2019-03-14T00:00:00","date_gmt":"2019-03-13T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/le-syndrome-du-canal-carpien-attelle-nocturne-ou-infiltration-de-corticosteroides\/"},"modified":"2026-05-07T19:11:58","modified_gmt":"2026-05-07T17:11:58","slug":"le-syndrome-du-canal-carpien-attelle-nocturne-ou-infiltration-de-corticosteroides","status":"publish","type":"post","link":"https:\/\/beta.cbip.be\/fr\/le-syndrome-du-canal-carpien-attelle-nocturne-ou-infiltration-de-corticosteroides\/","title":{"rendered":"Le syndrome du canal carpien: attelle nocturne ou infiltration de corticost\u00e9ro\u00efdes?"},"content":{"rendered":"<p>Le <b>syndrome du canal carpien<\/b> (<b>SCC<\/b>) est une cause fr&eacute;quente de douleur &agrave; la main&#x002C; de picotements dans les doigts et d&rsquo;une diminution de la force. Un grand nombre de patients pr&eacute;sentant des sympt&ocirc;mes l&eacute;gers &agrave; mod&eacute;r&eacute;s peuvent &ecirc;tre trait&eacute;s de mani&egrave;re symptomatique en premi&egrave;re ligne&#x002C; l&rsquo;objectif &eacute;tant de soulager les sympt&ocirc;mes&#x002C; de limiter la perte fonctionnelle et d&rsquo;&eacute;viter une l&eacute;sion nerveuse. Par forme l&eacute;g&egrave;re on entend les patients pr&eacute;sentant une paresth&eacute;sie intermittente dans le territoire sensitif du nerf m&eacute;dian&#x002C; une sensation r&eacute;versible d&rsquo;engourdissement et une douleur idiopathique; la forme mod&eacute;r&eacute;e se d&eacute;finit par les m&ecirc;mes caract&eacute;ristiques&#x002C; sauf que les paresth&eacute;sies sont continues.<span class='folia-referentie-note'>1<\/span>&nbsp;En pr&eacute;sence de sympt&ocirc;mes d&rsquo;alarme tels qu&rsquo;une douleur continue&#x002C; une perte de sensibilit&eacute; ou de force et une atrophie musculaire&#x002C; il convient &eacute;videmment de r&eacute;f&eacute;rer le patient pour des examens compl&eacute;mentaires et une chirurgie. Les traitements conservateurs les plus utilis&eacute;s sont le port d&rsquo;une attelle nocturne ou l&rsquo;infiltration d&rsquo;un corticost&eacute;ro&iuml;de. D&rsquo;un c&ocirc;t&eacute; il existe des preuves limit&eacute;es de l&rsquo;efficacit&eacute; des attelles nocturnes (emp&ecirc;chant la flexion du poignet)&#x002C; d&rsquo;un autre c&ocirc;t&eacute;&#x002C; des preuves solides en faveur des infiltrations &agrave; plus court terme (apr&egrave;s 8 semaine).<span class='folia-referentie-note'>2&#x002C;3<\/span>&nbsp;Cependant&#x002C; l&rsquo;effet &agrave; long terme n&rsquo;est pas tr&egrave;s clair. Une RCT rigoureusement con&ccedil;ue (&eacute;tude INSTINCTS)&#x002C; incluant 212 patients&#x002C; a compar&eacute; l&rsquo;efficacit&eacute; de ces deux traitements chez des patients pr&eacute;sentant une forme l&eacute;g&egrave;re &agrave; mod&eacute;r&eacute;e du syndrome du canal carpien. Les auteurs concluent qu&rsquo;une infiltration unique d&rsquo;un corticost&eacute;ro&iuml;de (dans ce cas-ci&#x002C; 20 mg de m&eacute;thylprednisolone) aboutit &agrave; un effet limit&eacute;&#x002C; cliniquement pertinent&#x002C; apr&egrave;s une &eacute;valuation &agrave; 6 semaines&#x002C; en comparaison avec 6 semaines d&rsquo;attelle nocturne (diff&eacute;rence moyenne de &ndash;0&#x002C;32&nbsp;; IC &agrave; 95% &ndash;0&#x002C;48 &agrave; &ndash;0&#x002C;16). L&rsquo;effet positif de l&rsquo;infiltration du corticost&eacute;ro&iuml;de se maintient jusqu&rsquo;&agrave; 6 mois&#x002C; mais compte tenu de l&rsquo;am&eacute;lioration suppl&eacute;mentaire des sympt&ocirc;mes obtenue avec le port continu de l&rsquo;attelle nocturne&#x002C; les diff&eacute;rences entre les deux traitements apr&egrave;s 6 mois sont minimes et ne sont plus statistiquement significatives. Aucun effet ind&eacute;sirable grave ou impr&eacute;vu n&rsquo;a &eacute;t&eacute; observ&eacute;. On notera par ailleurs que dans l&rsquo;&eacute;tude&#x002C; les r&eacute;sultats th&eacute;rapeutiques sont meilleurs lorsque le choix du traitement correspondait &agrave; la pr&eacute;f&eacute;rence du patient.&nbsp;Apr&egrave;s 6 mois&#x002C; un tiers des patients continuent toutefois &agrave; pr&eacute;senter des sympt&ocirc;mes ou sont r&eacute;f&eacute;r&eacute;s pour une intervention chirurgicale.<br \/> En guise de <b>conclusion<\/b>&#x002C; on peut dire qu&rsquo;<i>il ressort des donn&eacute;es r&eacute;centes qu&rsquo;une infiltration unique d&rsquo;un corticost&eacute;ro&iuml;de en premi&egrave;re ligne&#x002C; a un effet plus rapide&#x002C; &agrave; court terme&#x002C; que l&rsquo;attelle nocturne&#x002C; dans les formes l&eacute;g&egrave;res et mod&eacute;r&eacute;es du syndrome du canal carpien. L&rsquo;effet &agrave; long terme n&rsquo;est pas clair&#x002C; &eacute;tant donn&eacute; que lors de l&rsquo;&eacute;valuation apr&egrave;s 6 mois de l&rsquo;infiltration unique&#x002C; compar&eacute;e au port continu d&rsquo;une attelle&#x002C; on n&rsquo;observe plus de diff&eacute;rence entre les deux traitements<\/i><em>.<\/em><span class='folia-referentie-note'>1&#x002C;4<\/span><\/p>\n<h2>Sources sp&eacute;cifiques<\/h2>\n<p> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Chesterton L. et al. The clinical and cost-effectiveness of corticosteroid injection versus night splints for carpal tunnel syndrome (INSTINCTS trial): an open-label&#x002C; parallel group&#x002C; randomised controlled trial. Lancet 2018; 392: 1423&ndash;33.<br \/> <span class='folia-referentie-nummer'>2&nbsp;<\/span>Page M. et al. Splinting for carpal tunnel syndrome. Cochrane Database of systematic reviews. 11 July 2012.<br \/> <span class='folia-referentie-nummer'>3&nbsp;<\/span>Premiers Choix Revue Prescrire. Syndrome du canal carpien. Actualisation Janvier 2018.<br \/> <span class='folia-referentie-nummer'>4&nbsp;<\/span>Atroshi A. Steroid injection or wrist splint for first-time carpal tunnel syndrome? Lancet 2018; 392: 1383-1384.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syndrome du canal carpien (SCC) est une cause fr&eacute;quente  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,62],"tags":[20213,20224],"class_list":["post-175605","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2019-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=175605"}],"version-history":[{"count":1,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175605\/revisions"}],"predecessor-version":[{"id":178189,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175605\/revisions\/178189"}],"wp:attachment":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=175605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=175605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=175605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}