{"id":175639,"date":"2018-09-01T00:00:00","date_gmt":"2018-08-31T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/un-traitement-de-lhepatite-c-a-un-cout-beaucoup-moins-eleve-nest-pas-une-option-inaccessible\/"},"modified":"2026-05-07T19:12:01","modified_gmt":"2026-05-07T17:12:01","slug":"un-traitement-de-lhepatite-c-a-un-cout-beaucoup-moins-eleve-nest-pas-une-option-inaccessible","status":"publish","type":"post","link":"https:\/\/beta.cbip.be\/fr\/un-traitement-de-lhepatite-c-a-un-cout-beaucoup-moins-eleve-nest-pas-une-option-inaccessible\/","title":{"rendered":"Un traitement de l\u2019h\u00e9patite C \u00e0 un co\u00fbt beaucoup moins \u00e9lev\u00e9 n\u2019est pas une option inaccessible"},"content":{"rendered":"<p>Les antiviraux oraux &agrave; action directe repr&eacute;sentent une avanc&eacute;e dans le traitement de l&rsquo;h&eacute;patite C. Cependant&#x002C; ils sont tr&egrave;s co&ucirc;teux [voir <a href='https:\/\/www.cbip.be\/fr\/articles\/2687?folia=2683'>Folia f&eacute;vrier 2017<\/a>] et leurs effets b&eacute;n&eacute;fiques en termes de r&eacute;ponse virologique soutenue &agrave; 12 semaines (RVS12&#x002C; c.-&agrave;-d. l&rsquo;absence de virus dans le sang 12 semaines apr&egrave;s le traitement antiviral) doivent &ecirc;tre compl&eacute;t&eacute;s par des donn&eacute;es &agrave; long terme sur le risque de rechute et sur la morbidit&eacute; et la mortalit&eacute; [voir <a href='https:\/\/www.cbip.be\/fr\/articles\/2245?folia=2197'>Folia septembre 2014<\/a> et <a href='https:\/\/www.cbip.be\/fr\/articles\/2802?folia=2798'>novembre 2017<\/a>&#x002C; et <a href='https:\/\/www.cbip.be\/fr\/chapters\/12?frag=25130'>R&eacute;pertoire chapitre 11.4.5.<\/a>]. L&rsquo;<a href='https:\/\/www.who.int\/hepatitis\/publications\/hep-c-access-report-2018\/en\/'>Organisation Mondiale de la Sant&eacute;<\/a> s&rsquo;est fix&eacute; comme objectif que 80% des patients infect&eacute;s par l&rsquo;h&eacute;patite C dans le monde soient trait&eacute;s d&rsquo;ici 2030.&nbsp; Le co&ucirc;t &eacute;lev&eacute; d&rsquo;un traitement (malgr&eacute; un faible prix &agrave; la production<span class='folia-referentie-note'>1<\/span>) reste un obstacle majeur &agrave; l&rsquo;acc&egrave;s &agrave; ces m&eacute;dicaments. &nbsp;Dans les pays &agrave; revenu &eacute;lev&eacute;&#x002C; y compris en Belgique&#x002C; le remboursement n&rsquo;est effectu&eacute; que dans des conditions strictes. Dans certains des pays &agrave; faibles et moyens revenus (entre autres Egypte&#x002C; Pakistan et Inde)&#x002C; on a r&eacute;ussi &agrave; r&eacute;duire consid&eacute;rablement le prix du traitement gr&acirc;ce &agrave; la disponibilit&eacute; de versions g&eacute;n&eacute;riques&#x002C; entre autres&#x002C; du sofosbuvir&#x002C; du l&eacute;dipasvir et du daclatasvir (environ 500 dollars pour un traitement de 12 semaines avec le sofosbuvir + l&eacute;dipasvir<a href='#Nota'>*<\/a>).<span class='folia-referentie-note'>2<\/span> En outre&#x002C; il existe &eacute;galement des organisations &agrave; but non lucratif qui&#x002C; afin d&rsquo;am&eacute;liorer l&rsquo;acc&egrave;s &agrave; ces m&eacute;dicaments dans les pays &agrave; faible revenu&#x002C; aident &agrave; d&eacute;velopper de nouveaux m&eacute;dicaments de cette classe&#x002C; comme le ravidasvir&#x002C; et cofinancent de larges &eacute;tudes cliniques avec ces m&eacute;dicaments.&nbsp; Il a &eacute;t&eacute; r&eacute;cemment rapport&eacute; que l&rsquo;association sofosbuvir + ravidasvir est prometteuse pour le traitement de l&rsquo;h&eacute;patite C&#x002C; avec un co&ucirc;t possible de seulement 300 dollars pour un traitement de 12 semaines.<span class='folia-referentie-note'>3<\/span><strong> <\/strong>Il est commercialement improbable que des prix aussi bas seront propos&eacute;s en Belgique &ldquo;prosp&egrave;re&rdquo;.<br \/> <strong>Commentaire du CBIP<\/strong>. C&rsquo;est la t&acirc;che des d&eacute;cideurs politiques de continuer &agrave; n&eacute;gocier avec les entreprises&#x002C; &eacute;galement pour les antiviraux &agrave; action directe contre l&rsquo;h&eacute;patite C&#x002C; afin d&rsquo;arriver &agrave; un prix transparent&#x002C; justifiable et &eacute;quitable [voir aussi l&rsquo;article &ldquo;Combien peuvent co&ucirc;ter les m&eacute;dicaments ?&nbsp; L&rsquo;exemple des m&eacute;dicaments contre l&rsquo;h&eacute;patite C&quot;&nbsp;dans les <a href='https:\/\/www.cbip.be\/fr\/articles\/2687?folia=2683'>Folia de f&eacute;vrier 2017<\/a>]. Dans le cas concret de ces antiviraux contre l&rsquo;h&eacute;patite C&#x002C; il peut &ecirc;tre envisag&eacute;&#x002C; dans certains cas&#x002C; de reporter le traitement&#x002C; par exemple lorsqu&rsquo;il n&rsquo;y a pas d&rsquo;urgence clinique&#x002C; en attendant des variantes moins ch&egrave;res.<\/p>\n<p><a href='#Nota'>*<\/a><u>&Agrave; titre de comparaison<\/u> : pour la sp&eacute;cialit&eacute; &agrave; base de sofosbuvir + l&eacute;dipasvir (Harvoni&reg;) en Belgique&#x002C; le CBIP mentionne un prix de 18.285 &euro; par conditionnement (c&rsquo;est le prix ex-usine&rdquo; + 6% TVA&#x002C; sans tenir compte des marges de n&eacute;gociation entre l&rsquo;h&ocirc;pital et l&rsquo;entreprise).&nbsp; Cela repr&eacute;sente un co&ucirc;t d&rsquo;environ 55.000 &euro; pour un traitement de 12 semaines.&nbsp; Le prix r&eacute;el pay&eacute; par l&rsquo;INAMI (dans les cas o&ugrave; les conditions de remboursement ont &eacute;t&eacute; respect&eacute;es) n&rsquo;est pas connu &eacute;tant donn&eacute; que pour de telles sp&eacute;cialit&eacute;s les accords de fixation de prix entre les autorit&eacute;s et les entreprises sont dans de nombreux cas confidentiels.<\/p>\n<h2>Sources sp&eacute;cifiques<\/h2>\n<p> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> <a href='https:\/\/1.%20https:\/\/www.who.int\/hepatitis\/news-events\/hep-c-access-report-2018-key-messages\/en\/'>https:\/\/www.who.int\/hepatitis\/news-events\/hep-c-access-report-2018-key-messages\/en\/\u200b<\/a><br \/> <span class='folia-referentie-nummer'>2<\/span>&nbsp;<a href='https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/hepatitis-c'>https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/hepatitis-c\u200b<\/a><br \/> <a href='https:\/\/www.who.int\/medicines\/areas\/access\/hepCtreat_key_facts\/en\/'>https:\/\/www.who.int\/medicines\/areas\/access\/hepCtreat_key_facts\/en\/<\/a><br \/> <span class='folia-referentie-nummer'>3<\/span> <a href='https:\/\/www.dndi.org\/2018\/media-centre\/press-releases\/new-affordable-hepatitis-c-combination-treatment-shows-97-cure-rate\/'>https:\/\/www.dndi.org\/2018\/media-centre\/press-releases\/new-affordable-hepatitis-c-combination-treatment-shows-97-cure-rate\/<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les antiviraux oraux &agrave; action directe repr&eacute;sentent une avanc&eacute;e dans  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,63],"tags":[20213,20224],"class_list":["post-175639","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2018-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=175639"}],"version-history":[{"count":1,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175639\/revisions"}],"predecessor-version":[{"id":178225,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175639\/revisions\/178225"}],"wp:attachment":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=175639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=175639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=175639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}