{"id":175705,"date":"2017-10-01T00:00:00","date_gmt":"2017-09-30T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/commentaire-le-glycerol-est-il-un-antitussif-efficace-chez-lenfant\/"},"modified":"2026-05-07T19:12:05","modified_gmt":"2026-05-07T17:12:05","slug":"commentaire-le-glycerol-est-il-un-antitussif-efficace-chez-lenfant","status":"publish","type":"post","link":"https:\/\/beta.cbip.be\/fr\/commentaire-le-glycerol-est-il-un-antitussif-efficace-chez-lenfant\/","title":{"rendered":"Commentaire: le glyc\u00e9rol est-il un antitussif efficace chez l\u2019enfant?"},"content":{"rendered":"<p>Un lecteur nous a questionn&eacute; au sujet de l&rsquo;efficacit&eacute; de Balso Kids&reg;&#x002C; un dispositif m&eacute;dical sous forme de sirop contenant du <strong>glyc&eacute;rol <\/strong>qui est propos&eacute; pour le traitement de la toux s&egrave;che chez les jeunes enfants (6 mois &agrave; 6 ans)&#x002C; une tranche d&rsquo;&acirc;ge dans laquelle les antitussifs classiques sont contre-indiqu&eacute;s.<\/p>\n<ul>\n<li>\n<p>Dans l&rsquo;ouvrage de r&eacute;f&eacute;rence <em>Martindale<\/em> le glyc&eacute;rol est mentionn&eacute; parmi les &eacute;mollients &quot;<em>demulcents<\/em>&quot;&#x002C; c.-&agrave;-d. des m&eacute;dicaments adoucissants. De tels produits&#x002C; parmi lesquels on retrouve aussi le miel&#x002C; la r&eacute;glisse et le sirop de saccharose&#x002C; formeraient un film protecteur sur la muqueuse pharyng&eacute;e&#x002C; diminuant ainsi l&rsquo;irritation locale.<\/p>\n<\/li>\n<li>\n<p>Aucune &eacute;tude n&rsquo;ayant &eacute;t&eacute; trouv&eacute;e concernant l&rsquo;efficacit&eacute; du glyc&eacute;rol dans la toux&#x002C; aucune recommandation concr&egrave;te ne peut &ecirc;tre formul&eacute;e en ce qui concerne le groupe cible&#x002C; la posologie&#x002C; la dur&eacute;e de traitement etc.<\/p>\n<\/li>\n<li>\n<p>Le nom de Balso Kids&reg; n&rsquo;est pas enregistr&eacute; en tant que m&eacute;dicament. Ce produit est en vente libre sous forme de&nbsp;dispositif m&eacute;dical. Les exigences pour les dispositifs m&eacute;dicaux sont diff&eacute;rentes de celles applicables aux m&eacute;dicaments&#x002C; avec par exemple des exigences beaucoup moins strictes ence qui concerne les preuves d&rsquo;efficacit&eacute;. Il existe au sein de l&rsquo;AFMPS une cellule qui est charg&eacute;e de collecter et d&rsquo;&eacute;valuer les incidents survenus avec des dispositifs m&eacute;dicaux (mat&eacute;riovigilance) [pour plus de d&eacute;tails sur les dispositifs m&eacute;dicaux&#x002C; voir <a href='https:\/\/www.fagg-afmps.be\/fr\/humain\/produits_de_sante\/dispositifs_medicaux'>www.fagg-afmps.be\/fr\/humain\/produits_de_sante\/dispositifs_medicaux<\/a> et <a href='https:\/\/www.afmps.be\/fr\/public_information\/dispositifs_medicaux'>www.afmps.be\/fr\/public_information\/dispositifs_medicaux<\/a>].<\/p>\n<\/li>\n<li>\n<p>Le nom de Balso Kids&reg; pr&ecirc;te &agrave; confusion; en effet&#x002C; Balsoclase Mucolyticum&reg; (contenant de la carbocist&eacute;ine&#x002C; un mucolytique) et Balsoclase Dextromethorfan&reg; (contenant du dextrom&eacute;thorphane&#x002C; un antitussif) sont tous deux enregistr&eacute;s comme m&eacute;dicaments&#x002C; &agrave; usage exclusif chez l&rsquo;adulte.<\/p>\n<\/li>\n<li>\n<p>En cas de toux chez l&rsquo;enfant&#x002C; il convient toujours d&rsquo;en rechercher la cause; dans la plupart des cas&#x002C; il s&rsquo;agit d&rsquo;une infection aigu&euml; des voies respiratoires sup&eacute;rieures d&rsquo;&eacute;volution spontan&eacute;ment favorable et ne n&eacute;cessitant pas de prise en charge m&eacute;dicamenteuse. En ce qui concerne l&rsquo;usage tr&egrave;s restrictif chez l&rsquo;enfant d&rsquo;antitussifs&#x002C; de gua&iuml;f&eacute;n&eacute;sine&#x002C; de pr&eacute;parations &agrave; usage nasal contenant des vasoconstricteurs et de mucolytiques&#x002C; voir <a href='https:\/\/www.cbip.be\/fr\/articles\/2176?folia=2146'>Folia de mars 2013<\/a> et <a href='https:\/\/www.cbip.be\/fr\/articles\/2151?folia=2102'>Folia de septembre 2013<\/a>.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Un lecteur nous a questionn&eacute; au sujet de l&rsquo;efficacit&eacute; de  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,175],"tags":[20213,20224],"class_list":["post-175705","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2017-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=175705"}],"version-history":[{"count":1,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175705\/revisions"}],"predecessor-version":[{"id":178290,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175705\/revisions\/178290"}],"wp:attachment":[{"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=175705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=175705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beta.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=175705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}